{"id":88029,"date":"2022-11-14T11:58:42","date_gmt":"2022-11-14T10:58:42","guid":{"rendered":"https:\/\/blog.wildix.com\/state-of-recruitment-today-ucc\/"},"modified":"2023-10-09T14:02:41","modified_gmt":"2023-10-09T12:02:41","slug":"stand-des-recruitments-heute-in-ucc","status":"publish","type":"post","link":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/","title":{"rendered":"Die Lage der Rekrutierung heute: Perspektiven eines HR-Managers"},"content":{"rendered":"<p><br \/>\nDie Personalabteilung ist eine komplexe Struktur, das Recruitment, Personalbindung, Beratung und Betreuung vereint und diese Vorteile dann an andere Gesch\u00e4ftsbereiche im Unternehmen weitergibt. Heutzutage steht sie vor vielen Herausforderungen. Diese Herausforderungen reichen von Problemen wie der sich \u00e4ndernden Rechtslage in verschiedenen L\u00e4ndern bis hin zum aktuellen Druck, die richtigen Mitarbeiter an den geeigneten Arbeitspl\u00e4tzen einzustellen.<\/p>\n<p><!--more--><\/p>\n<h2><strong>Die Umst\u00e4nde haben sich ge\u00e4ndert<\/strong><\/h2>\n<p>In den letzten vier Jahren hat sich viel ver\u00e4ndert, und nicht nur aufgrund der COVID-19-Pandemie. Die Generation der Babyboomer geht nun langsam in die Rente, und auch die Generation-X ist nicht mehr weit davon entfernt. Zudem haben die Millennials und die Mitarbeiter der Generation-Z haben schon vor der Pandemie eine deutliche Ver\u00e4nderung der Arbeitsmuster und -gewohnheiten erlebt.<\/p>\n<p>Die Technik war vorhanden und die M\u00f6glichkeit, von zu Hause aus zu arbeiten, nahm zu. Im Endeffekt hat die Pandemie lediglich den entscheidenden Ansto\u00df gegeben, um diese Arbeitsbedingungen zu schaffen.<\/p>\n<h3>Online Bewerbungsgespr\u00e4che sind der neue Standard<\/h3>\n<p>Vor Covid wurden die Vorstellungsgespr\u00e4che per Video als Teil eines Ganzen behandelt. Zur damaligen Zeit w\u00e4re es ungew\u00f6hnlich gewesen, einen kompletten Prozess von Anfang bis Ende ohne ein pers\u00f6nliches Gespr\u00e4ch zu haben. Mittlerweile hat sich jedoch jeder daran gew\u00f6hnt, s\u00e4mtliche Vorg\u00e4nge per Video zu erledigen. Es f\u00fchlt sich nicht mehr merkw\u00fcrdig oder ungewohnt an, dass wir uns noch nie pers\u00f6nlich getroffen haben.<\/p>\n<h3>Arbeit ist ortsunabh\u00e4ngig<\/h3>\n<p>In einem B\u00fcro zu arbeiten bedeutet, dass Sie vor Ort anwesend sein m\u00fcssen. Doch mit der zunehmenden Verbreitung der Remote-Arbeit ist der Standort nicht mehr so wichtig. Dadurch erweitert sich der Talentpool, auf den die Personalabteilung und die Personalbeschaffung zugreifen k\u00f6nnen. So k\u00f6nnen Sie auch nach F\u00e4higkeiten und Kompetenzen suchen, die in der Region nicht so verbreitet sind.<\/p>\n<p>Wir sollten auf den Markt h\u00f6ren, und es ist klar, dass die geografische Lage nicht so wichtig ist, wenn der Bewerber die f\u00fcr die Stelle erforderlichen F\u00e4higkeiten besitzt. Doch das Unternehmen muss sich auch darum bem\u00fchen, das Gef\u00fchl der Zugeh\u00f6rigkeit zu schaffen, das notwendig ist, damit sich die Mitarbeiter mit ihren Kollegen verbunden f\u00fchlen. Teambildung ist wichtig &#8211; aber sie muss sorgf\u00e4ltig durchdacht sein, damit sich jeder einbringen kann.<\/p>\n<h3>Work-Life Balance<\/h3>\n<p>Im Allgemeinen haben die Menschen die Priorit\u00e4ten in ihrem Leben \u00fcberdacht. Obwohl die Vorstellung, einen guten Job zu haben, ein wichtiges Ziel ist, achten immer mehr Menschen zuerst auf die Werte des Unternehmens. Flexibilit\u00e4t und Anpassungsf\u00e4higkeit an das moderne Arbeitsleben sind entscheidend. Die Unternehmen m\u00fcssen das unter Beweis stellen. Wenn Kandidaten von einem Personalvermittler oder einem Unternehmen auf LinkedIn angesprochen werden, wollen sie die Vorteile eines Arbeitgebers im Vergleich zu anderen Unternehmen sehen.<\/p>\n<p>Das bedeutet, dass sich das Unternehmen von seinen Mitbewerbern abheben muss &#8211; und das nicht nur durch seine Mission und Vision. Die Fragestellungen haben sich ge\u00e4ndert. Sie lauten nicht mehr &#8222;Warum wollen Sie f\u00fcr uns arbeiten&#8220;, sondern &#8222;Warum sollten Sie f\u00fcr uns arbeiten&#8220;. Die Dynamik hat sich verlagert.<\/p>\n<p>Im Zuge dieses Wandels hat sich auch die Vorstellung vom Ruf des Unternehmens ver\u00e4ndert. Es ist nicht mehr entscheidend, einen gro\u00dfen Namen zu haben, um neue Talente anzuziehen. Der Ruf eines Unternehmens beruht vielmehr auf der Unternehmenskultur. Entscheidend ist die Festlegung der Werte, nach denen wir arbeiten, und diese Werte m\u00fcssen in allen Regionen und Abteilungen beibehalten werden. Diese kulturelle Vereinheitlichung ersetzt die Pr\u00e4senz in einem B\u00fcro viel effektiver als jeder andere Faktor.<\/p>\n<h2><strong>\u00c4nderungen im Recruitment in den Regionen<\/strong><\/h2>\n<p>Als Personalleiterin von Wildix arbeite ich in zahlreichen Regionen: insbesondere in der EU, der Ukraine, Gro\u00dfbritannien und den Vereinigten Staaten. Jede dieser Regionen hat seinen eigenen Mikrokosmos voller Unterschiede.<\/p>\n<p>Im Gro\u00dfen und Ganzen sind alle diese Regionen von den Ver\u00e4nderungen betroffen. Dabei sind Arbeitspl\u00e4tze in den Bereichen Technik, Verwaltung, Finanzen und Vertrieb besonders stark von den branchenweiten \u00c4nderungen betroffen. Allerdings gibt es regionale Unterschiede, die von der lokalen Kultur, der Politik und den Arbeitsgewohnheiten abh\u00e4ngen. Einige L\u00e4nder sind widerstandsf\u00e4higer gegen Ver\u00e4nderungen, andere weniger.<\/p>\n<p>Nat\u00fcrlich gibt es auch innerhalb der L\u00e4nder Unterschiede. In St\u00e4dten mit besserer Anbindung sind die Ver\u00e4nderungen viel gr\u00f6\u00dfer als in l\u00e4ndlichen Gebieten. Au\u00dferdem gibt es leichte Unterschiede in der Altersdemografie. J\u00fcngere Mitarbeiter sind mit der Technologie besser vertraut und sch\u00e4tzen die M\u00f6glichkeit, von \u00fcberall aus arbeiten zu k\u00f6nnen. \u00c4ltere Mitarbeiter hingegen wissen die neu gewonnene M\u00f6glichkeit zu sch\u00e4tzen, nach ihren eigenen Bedingungen zu arbeiten, vor allem, wenn es um die Familie geht oder wenn sie es einfach leid sind, sich so stark der Arbeit zu widmen.<\/p>\n<h2><strong>Die UC&amp;C-Branche ist ein Nischenmarkt<\/strong><\/h2>\n<p>Der Talentpool ist bereits begrenzt, da wir in einer Nischenbranche t\u00e4tig sind. Im Vertrieb oder bei hochspezifischen technischen Profilen haben wir beobachtet, dass die Gehaltserwartungen gestiegen sind und dass die Leute ein stabileres Gehalt bevorzugen. Die F\u00e4higkeiten bleiben im Gro\u00dfen und Ganzen die gleichen, aber die potenziellen Mitarbeiter sind sich ihres Wertes f\u00fcr das Unternehmen bewusster. Auch die Inflation hat sich bemerkbar gemacht.<\/p>\n<p>Unternehmen in der UC&amp;C-Nische, wie z.B. unsere Partner, haben ebenfalls Schwierigkeiten, Talente zu rekrutieren und &#8211; was noch viel wichtiger ist &#8211; an sich zu binden, da das Angebot immer kleiner wird. Angesichts all dieser Ver\u00e4nderungen, wie z.B. der Unsicherheit in der Welt, erhalte ich jedes Mal, wenn ich mit einem Gesch\u00e4ftsf\u00fchrer oder einem CEO spreche, dieselbe Antwort auf die Frage nach den Herausforderungen, mit denen sie konfrontiert sind: die Talentsuche.<\/p>\n<p>Es geht also um das Verst\u00e4ndnis, wie man auf dem Markt wettbewerbsf\u00e4hig bleibt. Es dreht sich nicht nur um den Job &#8211; warum sollte jemand f\u00fcr uns arbeiten? Ich hatte die Gelegenheit, einer Gruppe von Wildix-Partnern einen Vortrag \u00fcber die Herausforderungen zu halten, denen wir uns im Personalwesen gegen\u00fcbersehen. Sie waren sehr daran interessiert zu erfahren, was wir tun, um dieses Problem zu bew\u00e4ltigen.<\/p>\n<h3>Kleinere Unternehmen haben oft Schwierigkeiten<\/h3>\n<p>Kleinere Unternehmen haben oft keine eigene Personalabteilung, was alles ein wenig schwieriger macht. Sie haben Probleme, weil ein CEO oder ein Unternehmensgr\u00fcnder, der sich um das Recruitment k\u00fcmmert, oft eine ganz andere Herangehensweise hat als ein Personalverantwortlicher. Das kann zu langfristigen Problemen f\u00fchren. Selbst C-Level-F\u00fchrungskr\u00e4fte, die HR studieren, haben nicht t\u00e4glich die Zeit, sich das Feedback der Mitarbeiter anzuh\u00f6ren oder mit denjenigen, die aktiv am Recruitment beteiligt sind, \u00fcber ihre spezifischen Bed\u00fcrfnisse zu sprechen.<\/p>\n<p>Die kleineren Unternehmen investieren vielleicht nicht viel in die Personalabteilung. In einigen F\u00e4llen lagern sie ihre HR-Funktionen aus. Vielleicht brauchen sie einen Verk\u00e4ufer, aber welche Art von Verk\u00e4ufer brauchen sie? Ben\u00f6tigen sie jemanden mit Erfahrung in der Branche oder sind sie in der Lage, Vertriebsmitarbeiter auszubilden? Die Ersteren werden vielleicht in ein paar Jahren gehen, w\u00e4hrend die Letzteren vielleicht bleiben, weil Sie sie gut ausgebildet haben und sie engagierter sind.<\/p>\n<p>Kleinere Unternehmen m\u00fcssen diese Stelle manchmal besetzen und entscheiden sich daher f\u00fcr die erste Person, die sich bewirbt und den vagen Parametern entspricht, was dazu f\u00fchren kann, dass die falsche Person in der falschen Position eingesetzt wird.<\/p>\n<p>Das kann zu langfristigen Problemen f\u00fchren, insbesondere wenn das Unternehmen expandiert und ein eigenes Team f\u00fcr Personal oder Recruitment aufbauen m\u00f6chte.<\/p>\n<h2><strong>Recruitment Strategie w\u00e4hrend der Great Resignation<\/strong><\/h2>\n<p>Das alles wirkt sich auf unsere Strategie aus. Es ist eine Herausforderung, aber auch aufregend &#8211; ich arbeite t\u00e4glich mit der Personalabteilung zusammen, und Herausforderungen bedeuten Wachstum und neue M\u00f6glichkeiten.<\/p>\n<p>Beim Recruitment versucht Wildix jetzt, die aktuelle Belegschaft und ihre Bed\u00fcrfnisse zu verstehen. Anschlie\u00dfend befassen wir uns mit der Umschulung und Fortbildung &#8211; k\u00f6nnen Mitarbeiter innerhalb des Unternehmens f\u00fcr h\u00f6here Positionen oder Nischenpositionen ausgebildet werden? Wir holen uns Feedback von den Mitarbeitern:<\/p>\n<ul>\n<li>Bed\u00fcrfnisse<\/li>\n<li>Interessen<\/li>\n<li>Vorstellungen von der beruflichen Entwicklung<\/li>\n<li>Werte und deren \u00dcbereinstimmung mit den Unternehmenswerten<\/li>\n<li>Ideen<\/li>\n<li>Initiativen<\/li>\n<\/ul>\n<p>Alle diese Punkte konzentrieren sich auf das Engagement der Mitarbeiter, denn wir m\u00fcssen ihnen helfen, zum wichtigsten Bef\u00fcrworter des Unternehmens zu werden. Auf diese Weise k\u00f6nnen wir in unsere Mitarbeiter und Talente investieren und die Zahl der K\u00fcndigungen verringern.<\/p>\n<h3>Remote-Working Teil der Unternehmensmission<\/h3>\n<p>Wenn ein Job aus der Ferne erledigt werden kann, ziehen wir das auf jeden Fall in Betracht &#8211; es ist ein zentraler Bestandteil unserer Unternehmensmission. Der Standort muss in vielen F\u00e4llen kein Hindernis sein, so dass wir den Talentpool nicht einschr\u00e4nken wollen.<\/p>\n<p>Wir wollen auch einige Profile umstrukturieren, um uns auf Kernaufgaben zu konzentrieren und uns st\u00e4rker zu spezialisieren und zu fokussieren. Ein Beispiel daf\u00fcr w\u00e4re, dass unsere Vertriebsleiter keine Generalisten mehr sind und fast alles machen. Wir teilen ihre Aufgaben jetzt in zwei separate Jobs auf: einer ist vielleicht ein Landwirt &#8211; er k\u00fcmmert sich um unsere derzeitigen Partner &#8211; und einer ist ein J\u00e4ger &#8211; er sucht nach neuen Partnern.<\/p>\n<p>Au\u00dferdem bauen wir Karrierewege auf. Wir f\u00fchren Seniorit\u00e4tsstufen ein, z.B. von unseren Vertretern f\u00fcr Gesch\u00e4ftsentwicklung bis hin zu unseren Senior Country Managern und mehr. Dadurch k\u00f6nnen sich die Mitarbeiter innerhalb von Wildix weiterentwickeln und m\u00fcssen unser Unternehmen nicht verlassen, wenn sie aufsteigen wollen.<\/p>\n<p>Allerdings stellen wir manchmal auch ehrgeizige Fachkr\u00e4fte ein, die vielleicht nicht dem Idealprofil entsprechen, das wir suchen. Wir achten darauf, wichtige Soft Skills zu kombinieren und ihnen die n\u00f6tige Ausbildung zu bieten.<\/p>\n<h2><strong>Ausblick<\/strong><\/h2>\n<p>Es ist allerdings schwer zu sagen, ob diese \u00c4nderungen von Dauer sind. Derzeit spielen so viele Faktoren eine Rolle, ob es sich nun um neue L\u00f6sungen und Technologien oder um globale Themen wie den Klimawandel handelt. Allerdings bin ich zuversichtlich, dass nichts mehr so sein wird wie in den Tagen vor Covid &#8230; gleichzeitig wird aber auch nichts mehr so sein wie jetzt.<\/p>\n<p>Ich bin der Meinung, dass sich die HR-Abteilung eines Unternehmens an die sich ver\u00e4ndernden Realit\u00e4ten um sie herum anpassen muss. Nur auf diese Weise k\u00f6nnen sie \u00fcberleben.<\/p>\n<p><strong><em>Wenn Sie mehr \u00fcber Recruitment und Personalmanagement in der Technologiebranche erfahren m\u00f6chten,<\/em> <a href=\"https:\/\/www.wildix.com\/de\/wildix-magazine\/\" target=\"_blank\" rel=\"noopener\">abonnieren Sie unser kostenloses Magazin!<\/a><\/strong><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Personalabteilung ist eine komplexe Struktur, das Recruitment, Personalbindung, Beratung und Betreuung vereint und diese Vorteile dann an andere Gesch\u00e4ftsbereiche im Unternehmen weitergibt. Heutzutage steht sie vor vielen Herausforderungen. Diese Herausforderungen reichen von Problemen wie der sich \u00e4ndernden Rechtslage in verschiedenen L\u00e4ndern bis hin zum aktuellen Druck, die richtigen Mitarbeiter an den geeigneten Arbeitspl\u00e4tzen einzustellen.<\/p>\n","protected":false},"author":809,"featured_media":88023,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4198],"tags":[],"class_list":["post-88029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expertenperspektiven"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das Recruitment hat sich ver\u00e4ndert - hier erfahren Sie wie | Wildix<\/title>\n<meta name=\"description\" content=\"Das Recruitment hat sich in den letzten Jahren ver\u00e4ndert, deshalb ist es wichtig, dass die Branche mit diesem Wandel mith\u00e4lt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das Recruitment hat sich ver\u00e4ndert - hier erfahren Sie wie | Wildix\" \/>\n<meta property=\"og:description\" content=\"Das Recruitment hat sich in den letzten Jahren ver\u00e4ndert, deshalb ist es wichtig, dass die Branche mit diesem Wandel mith\u00e4lt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/\" \/>\n<meta property=\"og:site_name\" content=\"Wildix Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wildix.pbx\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-14T10:58:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-09T12:02:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wildix.com\/wp-content\/uploads\/2022\/11\/The-State-of-Recruitment-Today.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberta Terranova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/blog.wildix.com\/wp-content\/uploads\/2022\/11\/The-State-of-Recruitment-Today.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@WildixSrl\" \/>\n<meta name=\"twitter:site\" content=\"@WildixSrl\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberta Terranova\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/\"},\"author\":{\"name\":\"Roberta Terranova\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/person\\\/8b968ca9104acc008f9b5fb2105b2320\"},\"headline\":\"Die Lage der Rekrutierung heute: Perspektiven eines HR-Managers\",\"datePublished\":\"2022-11-14T10:58:42+00:00\",\"dateModified\":\"2023-10-09T12:02:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/\"},\"wordCount\":1736,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/The-State-of-Recruitment-Today.jpg\",\"articleSection\":[\"Expertenperspektiven\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/\",\"name\":\"Das Recruitment hat sich ver\u00e4ndert - hier erfahren Sie wie | Wildix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/The-State-of-Recruitment-Today.jpg\",\"datePublished\":\"2022-11-14T10:58:42+00:00\",\"dateModified\":\"2023-10-09T12:02:41+00:00\",\"description\":\"Das Recruitment hat sich in den letzten Jahren ver\u00e4ndert, deshalb ist es wichtig, dass die Branche mit diesem Wandel mith\u00e4lt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/The-State-of-Recruitment-Today.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/The-State-of-Recruitment-Today.jpg\",\"width\":1200,\"height\":630,\"caption\":\"The State of Recruitment Today: Perspectives From an HR Manager\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/stand-des-recruitments-heute-in-ucc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.wildix.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expertenperspektiven\",\"item\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/category\\\/expertenperspektiven\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Die Lage der Rekrutierung heute: Perspektiven eines HR-Managers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/\",\"name\":\"Wildix Blog\",\"description\":\"From VoIP to Unified Communications and WebRTC\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wildix.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#organization\",\"name\":\"Wildix\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Wildix-blog-logo.webp\",\"contentUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Wildix-blog-logo.webp\",\"width\":558,\"height\":250,\"caption\":\"Wildix\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wildix.pbx\",\"https:\\\/\\\/x.com\\\/WildixSrl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wildix-srl\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WildixPBX\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/person\\\/8b968ca9104acc008f9b5fb2105b2320\",\"name\":\"Roberta Terranova\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2a5fe0272e5aeed97896678b1b3b8b4f55dadc8ee76b3eef8a3e70f0549572f?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2a5fe0272e5aeed97896678b1b3b8b4f55dadc8ee76b3eef8a3e70f0549572f?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2a5fe0272e5aeed97896678b1b3b8b4f55dadc8ee76b3eef8a3e70f0549572f?s=96&d=retro&r=g\",\"caption\":\"Roberta Terranova\"},\"url\":\"https:\\\/\\\/blog.wildix.com\\\/de\\\/author\\\/roberta-terranova\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das Recruitment hat sich ver\u00e4ndert - hier erfahren Sie wie | Wildix","description":"Das Recruitment hat sich in den letzten Jahren ver\u00e4ndert, deshalb ist es wichtig, dass die Branche mit diesem Wandel mith\u00e4lt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/","og_locale":"de_DE","og_type":"article","og_title":"Das Recruitment hat sich ver\u00e4ndert - hier erfahren Sie wie | Wildix","og_description":"Das Recruitment hat sich in den letzten Jahren ver\u00e4ndert, deshalb ist es wichtig, dass die Branche mit diesem Wandel mith\u00e4lt.","og_url":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/","og_site_name":"Wildix Blog","article_publisher":"https:\/\/www.facebook.com\/wildix.pbx","article_published_time":"2022-11-14T10:58:42+00:00","article_modified_time":"2023-10-09T12:02:41+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2022\/11\/The-State-of-Recruitment-Today.jpg","type":"image\/jpeg"}],"author":"Roberta Terranova","twitter_card":"summary_large_image","twitter_image":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2022\/11\/The-State-of-Recruitment-Today.jpg","twitter_creator":"@WildixSrl","twitter_site":"@WildixSrl","twitter_misc":{"Verfasst von":"Roberta Terranova","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/#article","isPartOf":{"@id":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/"},"author":{"name":"Roberta Terranova","@id":"https:\/\/blog.wildix.com\/#\/schema\/person\/8b968ca9104acc008f9b5fb2105b2320"},"headline":"Die Lage der Rekrutierung heute: Perspektiven eines HR-Managers","datePublished":"2022-11-14T10:58:42+00:00","dateModified":"2023-10-09T12:02:41+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/"},"wordCount":1736,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wildix.com\/#organization"},"image":{"@id":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2022\/11\/The-State-of-Recruitment-Today.jpg","articleSection":["Expertenperspektiven"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/","url":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/","name":"Das Recruitment hat sich ver\u00e4ndert - hier erfahren Sie wie | Wildix","isPartOf":{"@id":"https:\/\/blog.wildix.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/#primaryimage"},"image":{"@id":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2022\/11\/The-State-of-Recruitment-Today.jpg","datePublished":"2022-11-14T10:58:42+00:00","dateModified":"2023-10-09T12:02:41+00:00","description":"Das Recruitment hat sich in den letzten Jahren ver\u00e4ndert, deshalb ist es wichtig, dass die Branche mit diesem Wandel mith\u00e4lt.","breadcrumb":{"@id":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/#primaryimage","url":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2022\/11\/The-State-of-Recruitment-Today.jpg","contentUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2022\/11\/The-State-of-Recruitment-Today.jpg","width":1200,"height":630,"caption":"The State of Recruitment Today: Perspectives From an HR Manager"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wildix.com\/de\/stand-des-recruitments-heute-in-ucc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.wildix.com\/"},{"@type":"ListItem","position":2,"name":"Expertenperspektiven","item":"https:\/\/blog.wildix.com\/de\/category\/expertenperspektiven\/"},{"@type":"ListItem","position":3,"name":"Die Lage der Rekrutierung heute: Perspektiven eines HR-Managers"}]},{"@type":"WebSite","@id":"https:\/\/blog.wildix.com\/#website","url":"https:\/\/blog.wildix.com\/","name":"Wildix Blog","description":"From VoIP to Unified Communications and WebRTC","publisher":{"@id":"https:\/\/blog.wildix.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wildix.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.wildix.com\/#organization","name":"Wildix","url":"https:\/\/blog.wildix.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.wildix.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2026\/05\/cropped-Wildix-blog-logo.webp","contentUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2026\/05\/cropped-Wildix-blog-logo.webp","width":558,"height":250,"caption":"Wildix"},"image":{"@id":"https:\/\/blog.wildix.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wildix.pbx","https:\/\/x.com\/WildixSrl","https:\/\/www.linkedin.com\/company\/wildix-srl","https:\/\/www.youtube.com\/user\/WildixPBX"]},{"@type":"Person","@id":"https:\/\/blog.wildix.com\/#\/schema\/person\/8b968ca9104acc008f9b5fb2105b2320","name":"Roberta Terranova","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c2a5fe0272e5aeed97896678b1b3b8b4f55dadc8ee76b3eef8a3e70f0549572f?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c2a5fe0272e5aeed97896678b1b3b8b4f55dadc8ee76b3eef8a3e70f0549572f?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c2a5fe0272e5aeed97896678b1b3b8b4f55dadc8ee76b3eef8a3e70f0549572f?s=96&d=retro&r=g","caption":"Roberta Terranova"},"url":"https:\/\/blog.wildix.com\/de\/author\/roberta-terranova\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wildix.com\/de\/wp-json\/wp\/v2\/posts\/88029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wildix.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wildix.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wildix.com\/de\/wp-json\/wp\/v2\/users\/809"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wildix.com\/de\/wp-json\/wp\/v2\/comments?post=88029"}],"version-history":[{"count":2,"href":"https:\/\/blog.wildix.com\/de\/wp-json\/wp\/v2\/posts\/88029\/revisions"}],"predecessor-version":[{"id":90839,"href":"https:\/\/blog.wildix.com\/de\/wp-json\/wp\/v2\/posts\/88029\/revisions\/90839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wildix.com\/de\/wp-json\/wp\/v2\/media\/88023"}],"wp:attachment":[{"href":"https:\/\/blog.wildix.com\/de\/wp-json\/wp\/v2\/media?parent=88029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wildix.com\/de\/wp-json\/wp\/v2\/categories?post=88029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wildix.com\/de\/wp-json\/wp\/v2\/tags?post=88029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}