{"id":710,"date":"2015-05-06T15:53:25","date_gmt":"2015-05-06T13:53:25","guid":{"rendered":"https:\/\/blog.wildix.com\/?p=710"},"modified":"2015-05-26T11:06:34","modified_gmt":"2015-05-26T09:06:34","slug":"wildix-business-collaboration-app-video","status":"publish","type":"post","link":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/","title":{"rendered":"Wildix Business Collaboration App  (VIDEO)"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Skype, WhatsApp, iMessage: grazie alla possibilit\u00e0 sempre pi\u00f9 diffusa di portare i propri dispositivi mobili sul posto di lavoro le <strong>applicazioni<\/strong> che oggi usiamo per comunicare sono <strong>molteplici<\/strong>.<\/span><\/p>\n<p class=\"p2\">La comunicazione \u00e8 <strong>comoda<\/strong> e <strong>veloce<\/strong>, ma spesso gli strumenti che utilizziamo sono davvero troppi e provocano <strong>distrazioni<\/strong>. Nelle applicazioni di messaggistica istantanea si mischiano messaggi privati e comunicazioni di lavoro importanti.<\/p>\n<p><!--more--><\/p>\n<p class=\"p2\">Siamo obbligati a uscire da Skype?<\/p>\n<p class=\"p1\"><span class=\"s1\">Dobbiamo disabilitare le notifiche di WhatsApp?<\/span><\/p>\n<p class=\"p2\">Il rischio che corriamo \u00e8 di ignorare, insieme ai messaggi che non sono pertinenti con il nostro lavoro, anche messaggi importanti da parte dei nostri colleghi.<\/p>\n<p class=\"p1\"><span class=\"s1\">Con l\u2019<strong>applicazione mobile<\/strong> di <strong>Wildix Collaboration<\/strong> questo non \u00e8 pi\u00f9 un problema.<\/p>\n<p><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Guarda il video e scopri i vantaggi:<\/span><\/p>\n<p>https:\/\/www.youtube.com\/watch?v=awTqSVdLnGY<\/p>\n<p class=\"p1\">\n","protected":false},"excerpt":{"rendered":"<p>Skype, WhatsApp, iMessage: grazie alla possibilit\u00e0 sempre pi\u00f9 diffusa di portare i propri dispositivi mobili sul posto di lavoro le applicazioni che oggi usiamo per comunicare sono molteplici. La comunicazione \u00e8 comoda e veloce, ma spesso gli strumenti che utilizziamo sono davvero troppi e provocano distrazioni. Nelle applicazioni di messaggistica istantanea si mischiano messaggi privati &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Wildix Business Collaboration App  (VIDEO)&#8221;<\/span><\/a><\/p>\n","protected":false},"author":10,"featured_media":719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4207],"tags":[],"class_list":["post-710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-product-highlights"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wildix Business Collaboration App (VIDEO) | Wildix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wildix Business Collaboration App (VIDEO) | Wildix\" \/>\n<meta property=\"og:description\" content=\"Skype, WhatsApp, iMessage: grazie alla possibilit\u00e0 sempre pi\u00f9 diffusa di portare i propri dispositivi mobili sul posto di lavoro le applicazioni che oggi usiamo per comunicare sono molteplici. La comunicazione \u00e8 comoda e veloce, ma spesso gli strumenti che utilizziamo sono davvero troppi e provocano distrazioni. Nelle applicazioni di messaggistica istantanea si mischiano messaggi privati &hellip; Leggi tutto &quot;Wildix Business Collaboration App (VIDEO)&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/\" \/>\n<meta property=\"og:site_name\" content=\"Wildix Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wildix.pbx\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-06T13:53:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-26T09:06:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-06-alle-16.05.00.png\" \/>\n\t<meta property=\"og:image:width\" content=\"624\" \/>\n\t<meta property=\"og:image:height\" content=\"344\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Moreno Perticaroli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WildixSrl\" \/>\n<meta name=\"twitter:site\" content=\"@WildixSrl\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moreno Perticaroli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/\"},\"author\":{\"name\":\"Moreno Perticaroli\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/person\\\/10e06581e1a75629e30abf860037f8bd\"},\"headline\":\"Wildix Business Collaboration App (VIDEO)\",\"datePublished\":\"2015-05-06T13:53:25+00:00\",\"dateModified\":\"2015-05-26T09:06:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/\"},\"wordCount\":127,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Schermata-2015-05-06-alle-16.05.00.png\",\"articleSection\":[\"Product &amp; Feature Highlights\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/\",\"name\":\"Wildix Business Collaboration App (VIDEO) | Wildix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Schermata-2015-05-06-alle-16.05.00.png\",\"datePublished\":\"2015-05-06T13:53:25+00:00\",\"dateModified\":\"2015-05-26T09:06:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Schermata-2015-05-06-alle-16.05.00.png\",\"contentUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Schermata-2015-05-06-alle-16.05.00.png\",\"width\":624,\"height\":344,\"caption\":\"Moreno | video\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/wildix-business-collaboration-app-video\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.wildix.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Punti salienti di prodotti e funzionalit\u00e0\",\"item\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/category\\\/punti-salienti-di-prodotti-e-funzionalita\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wildix Business Collaboration App (VIDEO)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/\",\"name\":\"Wildix Blog\",\"description\":\"Dal VoIP alle Unified Communication al WebRTC\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wildix.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#organization\",\"name\":\"Wildix\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Wildix-blog-logo.webp\",\"contentUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Wildix-blog-logo.webp\",\"width\":558,\"height\":250,\"caption\":\"Wildix\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wildix.pbx\",\"https:\\\/\\\/x.com\\\/WildixSrl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wildix-srl\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WildixPBX\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/person\\\/10e06581e1a75629e30abf860037f8bd\",\"name\":\"Moreno Perticaroli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1313382d9a18ba3a19a0fe0b7d108f061af9eb7e2bd2d0c11ec381b343c16e99?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1313382d9a18ba3a19a0fe0b7d108f061af9eb7e2bd2d0c11ec381b343c16e99?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1313382d9a18ba3a19a0fe0b7d108f061af9eb7e2bd2d0c11ec381b343c16e99?s=96&d=retro&r=g\",\"caption\":\"Moreno Perticaroli\"},\"description\":\"Wildix Area Manager - Ancona\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/author\\\/moreno-perticaroli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wildix Business Collaboration App (VIDEO) | Wildix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/","og_locale":"it_IT","og_type":"article","og_title":"Wildix Business Collaboration App (VIDEO) | Wildix","og_description":"Skype, WhatsApp, iMessage: grazie alla possibilit\u00e0 sempre pi\u00f9 diffusa di portare i propri dispositivi mobili sul posto di lavoro le applicazioni che oggi usiamo per comunicare sono molteplici. La comunicazione \u00e8 comoda e veloce, ma spesso gli strumenti che utilizziamo sono davvero troppi e provocano distrazioni. Nelle applicazioni di messaggistica istantanea si mischiano messaggi privati &hellip; Leggi tutto \"Wildix Business Collaboration App (VIDEO)\"","og_url":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/","og_site_name":"Wildix Blog","article_publisher":"https:\/\/www.facebook.com\/wildix.pbx","article_published_time":"2015-05-06T13:53:25+00:00","article_modified_time":"2015-05-26T09:06:34+00:00","og_image":[{"width":624,"height":344,"url":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-06-alle-16.05.00.png","type":"image\/png"}],"author":"Moreno Perticaroli","twitter_card":"summary_large_image","twitter_creator":"@WildixSrl","twitter_site":"@WildixSrl","twitter_misc":{"Scritto da":"Moreno Perticaroli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/#article","isPartOf":{"@id":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/"},"author":{"name":"Moreno Perticaroli","@id":"https:\/\/blog.wildix.com\/#\/schema\/person\/10e06581e1a75629e30abf860037f8bd"},"headline":"Wildix Business Collaboration App (VIDEO)","datePublished":"2015-05-06T13:53:25+00:00","dateModified":"2015-05-26T09:06:34+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/"},"wordCount":127,"commentCount":1,"publisher":{"@id":"https:\/\/blog.wildix.com\/#organization"},"image":{"@id":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-06-alle-16.05.00.png","articleSection":["Product &amp; Feature Highlights"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/","url":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/","name":"Wildix Business Collaboration App (VIDEO) | Wildix","isPartOf":{"@id":"https:\/\/blog.wildix.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/#primaryimage"},"image":{"@id":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-06-alle-16.05.00.png","datePublished":"2015-05-06T13:53:25+00:00","dateModified":"2015-05-26T09:06:34+00:00","breadcrumb":{"@id":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/#primaryimage","url":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-06-alle-16.05.00.png","contentUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-06-alle-16.05.00.png","width":624,"height":344,"caption":"Moreno | video"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wildix.com\/it\/wildix-business-collaboration-app-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.wildix.com\/"},{"@type":"ListItem","position":2,"name":"Punti salienti di prodotti e funzionalit\u00e0","item":"https:\/\/blog.wildix.com\/it\/category\/punti-salienti-di-prodotti-e-funzionalita\/"},{"@type":"ListItem","position":3,"name":"Wildix Business Collaboration App (VIDEO)"}]},{"@type":"WebSite","@id":"https:\/\/blog.wildix.com\/#website","url":"https:\/\/blog.wildix.com\/","name":"Wildix Blog","description":"Dal VoIP alle Unified Communication al WebRTC","publisher":{"@id":"https:\/\/blog.wildix.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wildix.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/blog.wildix.com\/#organization","name":"Wildix","url":"https:\/\/blog.wildix.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.wildix.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2026\/05\/cropped-Wildix-blog-logo.webp","contentUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2026\/05\/cropped-Wildix-blog-logo.webp","width":558,"height":250,"caption":"Wildix"},"image":{"@id":"https:\/\/blog.wildix.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wildix.pbx","https:\/\/x.com\/WildixSrl","https:\/\/www.linkedin.com\/company\/wildix-srl","https:\/\/www.youtube.com\/user\/WildixPBX"]},{"@type":"Person","@id":"https:\/\/blog.wildix.com\/#\/schema\/person\/10e06581e1a75629e30abf860037f8bd","name":"Moreno Perticaroli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1313382d9a18ba3a19a0fe0b7d108f061af9eb7e2bd2d0c11ec381b343c16e99?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1313382d9a18ba3a19a0fe0b7d108f061af9eb7e2bd2d0c11ec381b343c16e99?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1313382d9a18ba3a19a0fe0b7d108f061af9eb7e2bd2d0c11ec381b343c16e99?s=96&d=retro&r=g","caption":"Moreno Perticaroli"},"description":"Wildix Area Manager - Ancona","url":"https:\/\/blog.wildix.com\/it\/author\/moreno-perticaroli\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/posts\/710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/comments?post=710"}],"version-history":[{"count":0,"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/posts\/710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/media\/719"}],"wp:attachment":[{"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/media?parent=710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/categories?post=710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/tags?post=710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}