{"id":747,"date":"2015-05-27T14:19:14","date_gmt":"2015-05-27T12:19:14","guid":{"rendered":"https:\/\/blog.wildix.com\/?p=747"},"modified":"2015-06-11T12:29:06","modified_gmt":"2015-06-11T10:29:06","slug":"10-000-persone-nella-stessa-stanza","status":"publish","type":"post","link":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/","title":{"rendered":"10.000 persone nella stessa stanza"},"content":{"rendered":"<p>Hai due sedi in Italia poi hai deciso di aprire una sede in Cina, poi una in Australia, e adesso non sai pi\u00f9 cosa inventarti per riuscire a gestire la comunicazione interna.<!--more--><\/p>\n<p>Un sistema di comunicazione evoluto serve a gestire sia pi\u00f9 filiali sul territorio, anche nello stesso comune, che sedi estere a migliaia di chilometri di distanza.<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #ff0000;\">Il risparmio?<\/span><\/strong><\/p>\n<p>In termini economici, si arriva anche a un <b>dimezzamento dei costi del traffico telefonico<\/b> e delle infrastrutture, che vengono di gran lunga ridimensionate.<\/p>\n<p>In termini di produttivit\u00e0, il risparmio \u00e8 enorme,<b> il 20% in meno del tempo impiegato nelle comunicazioni interne*<\/b>, il che significa soddisfare pi\u00f9 richieste e avere pi\u00f9 tempo da dedicare ad altre attivit\u00e0 lavorative.<\/p>\n<p>Se un tuo collaboratore cambia spesso sede, <b>pu\u00f2 effettuare il proprio login sul telefono<\/b> della sede in cui si trova e essere reperibile al suo solito numero di interno.<\/p>\n<p>E&#8217; il caso di Laura, che lavora fra la sede di Trento e la sede tedesca di Wildix. Quando si sposta, le basta eseguire il login con il suo interno e la sua password, la stessa di Wildix Collaboration, per iniziare subito a utilizzare il telefono.<\/p>\n<p>Puoi avere<b> un gruppo di risposta<\/b> (call center) in paesi o Nazioni diverse e far arrivare le chiamate ai singoli operatori, attraverso un instradamento automatico delle chiamate. Aggiungere esempio<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><b>E\u2019 come avere 10.000 persone nella stessa stanza<\/b><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-medium wp-image-800 aligncenter\" src=\"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-19-alle-11.35.27-300x179.png\" alt=\"Schermata 2015-05-19 alle 11.35.27\" width=\"300\" height=\"179\" srcset=\"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-19-alle-11.35.27-300x179.png 300w, https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-19-alle-11.35.27-660x395.png 660w, https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-19-alle-11.35.27.png 726w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center;\"><strong>\u2026 con la differenza che cos\u00ec forse ci sarebbe un po\u2019 pi\u00f9 di confusione!<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La testimonianza della BCC dell&#8217;Adda e del Cremasco Cassa Rurale:<\/p>\n<p><img decoding=\"async\" class=\"  wp-image-802 alignleft\" src=\"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/BCC--300x85.gif\" alt=\"BCC\" width=\"275\" height=\"78\" \/><i>\u00a0\u201cC<\/i><i>ollegando in rete tutte le centrali telefoniche (WMS Network), abbiamo consentito a ognuno dei nostri <\/i><b><i>120 collaboratori delle 20 sedi della nostra banca<\/i><\/b><i> di contattare i propri colleghi in modo veloce e sicuro, generando un <\/i><b><i>risparmio del 20% del tempo<\/i><\/b><i> nelle comunicazioni interne e migliorando cos\u00ec l\u2019efficienza dei processi operativi.<\/i><br \/>\n<i>Con i telefoni Wildix inoltre ogni operatore pu\u00f2 <\/i><b><i>effettuare il proprio login <\/i><\/b><i>collegandosi all\u2019apparecchio telefonico a seconda della sede in cui si trova, assicurando in tale modo alla clientela la propria continua presenza.\u201d<\/i><\/p>\n<p><strong>Cesare Lombardi<br \/>\nResponsabile dell\u2019Area Organizzazione e Risorse<br \/>\nBCC dell&#8217;Adda e del Cremasco Cassa Rurale<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hai due sedi in Italia poi hai deciso di aprire una sede in Cina, poi una in Australia, e adesso non sai pi\u00f9 cosa inventarti per riuscire a gestire la comunicazione interna.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3543],"tags":[],"class_list":["post-747","post","type-post","status-publish","format-standard","hentry","category-expert-perspectives"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10.000 persone nella stessa stanza | Wildix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10.000 persone nella stessa stanza | Wildix\" \/>\n<meta property=\"og:description\" content=\"Hai due sedi in Italia poi hai deciso di aprire una sede in Cina, poi una in Australia, e adesso non sai pi\u00f9 cosa inventarti per riuscire a gestire la comunicazione interna.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Wildix Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wildix.pbx\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-27T12:19:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-11T10:29:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-19-alle-11.35.27.png\" \/>\n\t<meta property=\"og:image:width\" content=\"726\" \/>\n\t<meta property=\"og:image:height\" content=\"434\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emiliano Tomasoni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WildixSrl\" \/>\n<meta name=\"twitter:site\" content=\"@WildixSrl\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emiliano Tomasoni\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/\"},\"author\":{\"name\":\"Emiliano Tomasoni\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/person\\\/2728d570e4f18f1f7be9ea19633f3c9c\"},\"headline\":\"10.000 persone nella stessa stanza\",\"datePublished\":\"2015-05-27T12:19:14+00:00\",\"dateModified\":\"2015-06-11T10:29:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/\"},\"wordCount\":355,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Schermata-2015-05-19-alle-11.35.27-300x179.png\",\"articleSection\":[\"Expert Perspectives\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/\",\"name\":\"10.000 persone nella stessa stanza | Wildix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Schermata-2015-05-19-alle-11.35.27-300x179.png\",\"datePublished\":\"2015-05-27T12:19:14+00:00\",\"dateModified\":\"2015-06-11T10:29:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Schermata-2015-05-19-alle-11.35.27-300x179.png\",\"contentUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Schermata-2015-05-19-alle-11.35.27-300x179.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/10-000-persone-nella-stessa-stanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.wildix.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prospettive degli esperti\",\"item\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/category\\\/prospettive-degli-esperti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"10.000 persone nella stessa stanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/\",\"name\":\"Wildix Blog\",\"description\":\"Dal VoIP alle Unified Communication al WebRTC\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.wildix.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#organization\",\"name\":\"Wildix\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Wildix-blog-logo.webp\",\"contentUrl\":\"https:\\\/\\\/blog.wildix.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Wildix-blog-logo.webp\",\"width\":558,\"height\":250,\"caption\":\"Wildix\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wildix.pbx\",\"https:\\\/\\\/x.com\\\/WildixSrl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wildix-srl\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WildixPBX\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.wildix.com\\\/#\\\/schema\\\/person\\\/2728d570e4f18f1f7be9ea19633f3c9c\",\"name\":\"Emiliano Tomasoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c71abb1e3b90d5bd92a50fa51734395dbf8b3c29e5b7792675eab489fae3841f?s=96&d=retro&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c71abb1e3b90d5bd92a50fa51734395dbf8b3c29e5b7792675eab489fae3841f?s=96&d=retro&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c71abb1e3b90d5bd92a50fa51734395dbf8b3c29e5b7792675eab489fae3841f?s=96&d=retro&r=g\",\"caption\":\"Emiliano Tomasoni\"},\"sameAs\":[\"http:\\\/\\\/www.wildix.com\"],\"url\":\"https:\\\/\\\/blog.wildix.com\\\/it\\\/author\\\/emiliano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10.000 persone nella stessa stanza | Wildix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/","og_locale":"it_IT","og_type":"article","og_title":"10.000 persone nella stessa stanza | Wildix","og_description":"Hai due sedi in Italia poi hai deciso di aprire una sede in Cina, poi una in Australia, e adesso non sai pi\u00f9 cosa inventarti per riuscire a gestire la comunicazione interna.","og_url":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/","og_site_name":"Wildix Blog","article_publisher":"https:\/\/www.facebook.com\/wildix.pbx","article_published_time":"2015-05-27T12:19:14+00:00","article_modified_time":"2015-06-11T10:29:06+00:00","og_image":[{"width":726,"height":434,"url":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-19-alle-11.35.27.png","type":"image\/png"}],"author":"Emiliano Tomasoni","twitter_card":"summary_large_image","twitter_creator":"@WildixSrl","twitter_site":"@WildixSrl","twitter_misc":{"Scritto da":"Emiliano Tomasoni","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/#article","isPartOf":{"@id":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/"},"author":{"name":"Emiliano Tomasoni","@id":"https:\/\/blog.wildix.com\/#\/schema\/person\/2728d570e4f18f1f7be9ea19633f3c9c"},"headline":"10.000 persone nella stessa stanza","datePublished":"2015-05-27T12:19:14+00:00","dateModified":"2015-06-11T10:29:06+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/"},"wordCount":355,"commentCount":0,"publisher":{"@id":"https:\/\/blog.wildix.com\/#organization"},"image":{"@id":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-19-alle-11.35.27-300x179.png","articleSection":["Expert Perspectives"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/","url":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/","name":"10.000 persone nella stessa stanza | Wildix","isPartOf":{"@id":"https:\/\/blog.wildix.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/#primaryimage"},"image":{"@id":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-19-alle-11.35.27-300x179.png","datePublished":"2015-05-27T12:19:14+00:00","dateModified":"2015-06-11T10:29:06+00:00","breadcrumb":{"@id":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/#primaryimage","url":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-19-alle-11.35.27-300x179.png","contentUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2015\/05\/Schermata-2015-05-19-alle-11.35.27-300x179.png"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.wildix.com\/it\/10-000-persone-nella-stessa-stanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.wildix.com\/"},{"@type":"ListItem","position":2,"name":"Prospettive degli esperti","item":"https:\/\/blog.wildix.com\/it\/category\/prospettive-degli-esperti\/"},{"@type":"ListItem","position":3,"name":"10.000 persone nella stessa stanza"}]},{"@type":"WebSite","@id":"https:\/\/blog.wildix.com\/#website","url":"https:\/\/blog.wildix.com\/","name":"Wildix Blog","description":"Dal VoIP alle Unified Communication al WebRTC","publisher":{"@id":"https:\/\/blog.wildix.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.wildix.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/blog.wildix.com\/#organization","name":"Wildix","url":"https:\/\/blog.wildix.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.wildix.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2026\/05\/cropped-Wildix-blog-logo.webp","contentUrl":"https:\/\/blog.wildix.com\/wp-content\/uploads\/2026\/05\/cropped-Wildix-blog-logo.webp","width":558,"height":250,"caption":"Wildix"},"image":{"@id":"https:\/\/blog.wildix.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wildix.pbx","https:\/\/x.com\/WildixSrl","https:\/\/www.linkedin.com\/company\/wildix-srl","https:\/\/www.youtube.com\/user\/WildixPBX"]},{"@type":"Person","@id":"https:\/\/blog.wildix.com\/#\/schema\/person\/2728d570e4f18f1f7be9ea19633f3c9c","name":"Emiliano Tomasoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c71abb1e3b90d5bd92a50fa51734395dbf8b3c29e5b7792675eab489fae3841f?s=96&d=retro&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c71abb1e3b90d5bd92a50fa51734395dbf8b3c29e5b7792675eab489fae3841f?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c71abb1e3b90d5bd92a50fa51734395dbf8b3c29e5b7792675eab489fae3841f?s=96&d=retro&r=g","caption":"Emiliano Tomasoni"},"sameAs":["http:\/\/www.wildix.com"],"url":"https:\/\/blog.wildix.com\/it\/author\/emiliano\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/posts\/747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/comments?post=747"}],"version-history":[{"count":0,"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/posts\/747\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/media?parent=747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/categories?post=747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.wildix.com\/it\/wp-json\/wp\/v2\/tags?post=747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}